{"id":3150,"date":"2025-06-02T10:57:06","date_gmt":"2025-06-02T08:57:06","guid":{"rendered":"https:\/\/proxipel.ch\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\/"},"modified":"2026-07-14T17:55:12","modified_gmt":"2026-07-14T15:55:12","slug":"tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel","status":"publish","type":"page","link":"https:\/\/proxipel.ch\/es\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\/","title":{"rendered":"Tecnolog\u00eda m\u00f3vil y servicio in situ: una innovaci\u00f3n de Proxipel"},"content":{"rendered":"<h3><img decoding=\"async\" class=\"aligncenter wp-image-832 size-large\" src=\"https:\/\/proxipel.ch\/wp-content\/uploads\/2024\/10\/PHOTO-2024-10-11-15-51-08-e1729165184286-1024x358.jpg\" alt=\"\" width=\"1024\" height=\"358\" srcset=\"https:\/\/proxipel.ch\/wp-content\/uploads\/2024\/10\/PHOTO-2024-10-11-15-51-08-e1729165184286-980x551.jpg 980w, https:\/\/proxipel.ch\/wp-content\/uploads\/2024\/10\/PHOTO-2024-10-11-15-51-08-e1729165184286-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/h3>\n<p dir=\"auto\"><a href=\"https:\/\/proxipel.ch\/es\/\">Proxipel, tu unidad m\u00f3vil de peletizaci\u00f3n integral<\/a>, te presenta su innovaci\u00f3n. En el \u00e1mbito de la valorizaci\u00f3n de los residuos verdes y la producci\u00f3n de pellets de madera, la tecnolog\u00eda m\u00f3vil y los servicios in situ suponen un gran avance. Proxipel, una empresa pionera en este sector, ha desarrollado una soluci\u00f3n innovadora con su unidad m\u00f3vil de peletizaci\u00f3n, Proxiflex. Esta tecnolog\u00eda permite transformar los residuos verdes en pellets de madera de alta calidad directamente en el lugar de producci\u00f3n, ofreciendo as\u00ed una soluci\u00f3n ecol\u00f3gica, eficaz y econ\u00f3mica. En este art\u00edculo, vamos a explorar las ventajas de la tecnolog\u00eda m\u00f3vil y los servicios in situ, as\u00ed como el funcionamiento de Proxiflex.    <\/p>\n<h2>\u00bfQu\u00e9 son la tecnolog\u00eda m\u00f3vil y los servicios in situ?<\/h2>\n<p dir=\"auto\">La tecnolog\u00eda m\u00f3vil y los servicios in situ consisten en llevar la planta de producci\u00f3n directamente al lugar donde se encuentran las materias primas, en lugar de transportar estas materias a una planta fija. Este enfoque tiene varias ventajas, entre ellas la reducci\u00f3n de los costes de transporte, la minimizaci\u00f3n de la huella de carbono y la optimizaci\u00f3n de la eficiencia energ\u00e9tica. <\/p>\n<h2>Las ventajas de la tecnolog\u00eda m\u00f3vil y los servicios presenciales<\/h2>\n<ol>\n<li><strong>Reducci\u00f3n de los costes de transporte<\/strong>: Al acercar la planta de producci\u00f3n a las materias primas, la tecnolog\u00eda m\u00f3vil permite reducir considerablemente los costes de transporte. Esto resulta especialmente ventajoso en el caso de materias primas voluminosas y pesadas, como los residuos verdes y los residuos de madera. <\/li>\n<li><strong>Minimizaci\u00f3n de la huella de carbono<\/strong>: La reducci\u00f3n de las distancias de transporte ayuda a minimizar la huella de carbono. Al limitar las emisiones de gases de efecto invernadero relacionadas con el transporte, la tecnolog\u00eda m\u00f3vil y los servicios in situ contribuyen a la protecci\u00f3n del medio ambiente. <\/li>\n<li><strong>Optimizaci\u00f3n de la eficiencia energ\u00e9tica<\/strong>: La tecnolog\u00eda m\u00f3vil permite producir pellets de madera directamente en la propia planta de producci\u00f3n, lo que optimiza la eficiencia energ\u00e9tica. Los pellets se pueden consumir y comercializar inmediatamente despu\u00e9s de su producci\u00f3n, lo que reduce las p\u00e9rdidas de energ\u00eda relacionadas con el almacenamiento y el transporte. <\/li>\n<li><strong>Flexibilidad y adaptabilidad<\/strong>: Las unidades m\u00f3viles de producci\u00f3n, como Proxiflex, est\u00e1n dise\u00f1adas para ser f\u00e1ciles de transportar y adaptarse a diferentes tipos de materias primas. Esta flexibilidad permite responder a las necesidades espec\u00edficas de distintos sectores, como la agricultura, la silvicultura y las administraciones locales. <\/li>\n<\/ol>\n<h2>Proxiflex: La unidad m\u00f3vil de peletizaci\u00f3n de Proxipel<\/h2>\n<p dir=\"auto\">Proxipel ha desarrollado una unidad m\u00f3vil de peletizaci\u00f3n \u00fanica en el mundo: Proxiflex. Esta innovaci\u00f3n transforma los residuos verdes en pellets de madera de alta calidad que cumplen la norma ISO 17225. La unidad m\u00f3vil Proxiflex est\u00e1 dise\u00f1ada para integrarse totalmente en un semirremolque, ofreciendo una gran movilidad y una eficacia \u00f3ptima.  <\/p>\n<h2>C\u00f3mo funciona Proxiflex<\/h2>\n<ol>\n<li dir=\"auto\"><strong>Recogida y preparaci\u00f3n de las materias primas<\/strong>: Proxiflex cuenta con una tolva de carga con capacidad para materiales como el serr\u00edn o las astillas, con un tama\u00f1o de part\u00edcula de hasta 50 mm. Las materias primas se recogen y preparan directamente en la planta de producci\u00f3n. <\/li>\n<li dir=\"auto\"><strong>Secado<\/strong>: Proxiflex cuenta con un secador patentado que permite producir pellets a partir de materias primas con hasta un 50 % de humedad. El secador reduce el nivel de humedad de las materias primas hasta aproximadamente un 10-15 %, lo cual es fundamental para garantizar la calidad y la eficacia de los pellets finales. <\/li>\n<li dir=\"auto\"><strong>Compresi\u00f3n<\/strong>: A continuaci\u00f3n, las materias primas secas se comprimen a alta presi\u00f3n a trav\u00e9s de una matriz para formar gr\u00e1nulos. El calor generado durante la compresi\u00f3n activa la lignina natural de la madera, que act\u00faa como aglutinante para mantener unidos los gr\u00e1nulos. <\/li>\n<li dir=\"auto\"><strong>Enfriamiento y envasado<\/strong>: Los gr\u00e1nulos calientes se enfr\u00edan y se tamizan para eliminar las part\u00edculas finas. A continuaci\u00f3n, se envasan en sacos o a granel para su distribuci\u00f3n. <\/li>\n<\/ol>\n<h2>Las aplicaciones de la tecnolog\u00eda m\u00f3vil y los servicios presenciales<\/h2>\n<p dir=\"auto\">La tecnolog\u00eda m\u00f3vil y los servicios in situ ofrecen una soluci\u00f3n flexible y adaptable para el aprovechamiento de los residuos verdes y la producci\u00f3n de pellets de madera. Estos son algunos ejemplos de aplicaciones: <\/p>\n<ol>\n<li><strong>Agricultura<\/strong>: Las unidades m\u00f3viles de producci\u00f3n se pueden utilizar para transformar los residuos agr\u00edcolas en pellets, lo que ofrece una soluci\u00f3n de calefacci\u00f3n ecol\u00f3gica y econ\u00f3mica para las explotaciones agr\u00edcolas.<\/li>\n<li><strong>Silvicultura<\/strong>: Las unidades m\u00f3viles de producci\u00f3n se pueden utilizar para aprovechar los residuos de madera procedentes de la explotaci\u00f3n forestal, contribuyendo as\u00ed a la gesti\u00f3n sostenible de los bosques.<\/li>\n<li><strong>Administraciones locales<\/strong>: Las unidades m\u00f3viles de producci\u00f3n se pueden utilizar para transformar los residuos verdes generados por el mantenimiento de parques y jardines en pellets, ofreciendo as\u00ed una soluci\u00f3n de calefacci\u00f3n ecol\u00f3gica para los edificios p\u00fablicos.<\/li>\n<\/ol>\n<h2>Conclusi\u00f3n<\/h2>\n<p dir=\"auto\">La tecnolog\u00eda m\u00f3vil y los servicios in situ suponen un gran avance en el \u00e1mbito de la valorizaci\u00f3n de los residuos verdes y la producci\u00f3n de pellets de madera. Proxipel, con su unidad m\u00f3vil de peletizaci\u00f3n Proxiflex, ofrece una soluci\u00f3n innovadora, ecol\u00f3gica y eficaz para transformar los residuos verdes en pellets de alta calidad. Al reducir los costes de transporte, minimizar la huella de carbono y optimizar la eficiencia energ\u00e9tica, la tecnolog\u00eda m\u00f3vil y los servicios in situ contribuyen a la protecci\u00f3n del medio ambiente y a promover una econom\u00eda circular. Al adoptar esta tecnolog\u00eda, todos podemos contribuir a la transici\u00f3n hacia una econom\u00eda m\u00e1s sostenible y respetuosa con el medio ambiente.   <\/p>\n<h2 dir=\"auto\">M\u00e1s informaci\u00f3n sobre la tecnolog\u00eda m\u00f3vil y el servicio a domicilio:<\/h2>\n<ul>\n<li class=\"p1\">1.<i> <\/i><a href=\"https:\/\/proxipel.ch\/es\/molienda-y-granulacion\/\">Molienda y granulaci\u00f3n<\/a><\/li>\n<li class=\"p1\">2.<i> <\/i><a href=\"https:\/\/proxipel.ch\/es\/unidades-moviles-y-equipos\/\">Unidades m\u00f3viles y equipamiento<\/a><\/li>\n<\/ul>\n<h2>Servicios Proxiflex :<\/h2>\n<ul>\n<li><a href=\"https:\/\/proxipel.ch\/es\/proxiflex\/\">Nuestra soluci\u00f3n m\u00f3vil de granulaci\u00f3n<\/a><\/li>\n<li><a href=\"https:\/\/proxipel.ch\/es\/tecnologia\/\">Nuestra tecnolog\u00eda innovadora<\/a><\/li>\n<li><a href=\"https:\/\/proxipel.ch\/es\/alquiler-de-unidades\/\">Alquiler de una unidad m\u00f3vil de peletizaci\u00f3n<\/a><\/li>\n<li><a href=\"https:\/\/proxipel.ch\/es\/pellets\/\">Venta de pellets<\/a><\/li>\n<\/ul>\n<h2>Contacta con nosotros<\/h2>\n<ul>\n<li><a href=\"https:\/\/proxipel.ch\/es\/ponte-en-contacto-con\/\">soluci\u00f3n m\u00f3vil de granulaci\u00f3n<\/a><\/li>\n<li><a href=\"mailto:Info@proxipel.com\">Info@proxipel.com informar<\/a><\/li>\n<li>Tel : <a href=\"tel:+41218013349\">+41 21 801 33 49<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Proxipel, tu unidad m\u00f3vil de peletizaci\u00f3n integral, te presenta su innovaci\u00f3n. En el \u00e1mbito de la valorizaci\u00f3n de los residuos verdes y la producci\u00f3n de pellets de madera, la tecnolog\u00eda m\u00f3vil y los servicios in situ suponen un gran avance. Proxipel, una empresa pionera en este sector, ha desarrollado una soluci\u00f3n innovadora con su unidad [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":1231,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-3150","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tecnolog\u00eda m\u00f3vil y servicio in situ: una innovaci\u00f3n de Proxipel - Proxipel<\/title>\n<meta name=\"description\" content=\"Descubre la tecnolog\u00eda m\u00f3vil de Proxipel para convertir los residuos verdes en pellets de madera, una soluci\u00f3n ecol\u00f3gica y eficaz que se puede llevar a cabo in situ\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proxipel.ch\/es\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tecnolog\u00eda m\u00f3vil y servicio in situ: una innovaci\u00f3n de Proxipel - Proxipel\" \/>\n<meta property=\"og:description\" content=\"Descubre la tecnolog\u00eda m\u00f3vil de Proxipel para convertir los residuos verdes en pellets de madera, una soluci\u00f3n ecol\u00f3gica y eficaz que se puede llevar a cabo in situ\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proxipel.ch\/es\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxipel\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T15:55:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proxipel.ch\/wp-content\/uploads\/2025\/01\/camion-usine-pellet.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"807\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proxipel.ch\\\/es\\\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\\\/\",\"url\":\"https:\\\/\\\/proxipel.ch\\\/es\\\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\\\/\",\"name\":\"Tecnolog\u00eda m\u00f3vil y servicio in situ: una innovaci\u00f3n de Proxipel - Proxipel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proxipel.ch\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proxipel.ch\\\/es\\\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proxipel.ch\\\/es\\\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proxipel.ch\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/camion-usine-pellet.webp\",\"datePublished\":\"2025-06-02T08:57:06+00:00\",\"dateModified\":\"2026-07-14T15:55:12+00:00\",\"description\":\"Descubre la tecnolog\u00eda m\u00f3vil de Proxipel para convertir los residuos verdes en pellets de madera, una soluci\u00f3n ecol\u00f3gica y eficaz que se puede llevar a cabo in situ\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proxipel.ch\\\/es\\\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proxipel.ch\\\/es\\\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/proxipel.ch\\\/es\\\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proxipel.ch\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/camion-usine-pellet.webp\",\"contentUrl\":\"https:\\\/\\\/proxipel.ch\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/camion-usine-pellet.webp\",\"width\":1600,\"height\":807,\"caption\":\"unit\u00e9 mobile de pelletisation int\u00e9grale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proxipel.ch\\\/es\\\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/proxipel.ch\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tecnolog\u00eda m\u00f3vil y servicio in situ: una innovaci\u00f3n de Proxipel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proxipel.ch\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/proxipel.ch\\\/es\\\/\",\"name\":\"Proxipel\",\"description\":\"La premi\u00e8re unit\u00e9 mobile de pelletisation int\u00e9grale\",\"publisher\":{\"@id\":\"https:\\\/\\\/proxipel.ch\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proxipel.ch\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proxipel.ch\\\/es\\\/#organization\",\"name\":\"Proxipel\",\"url\":\"https:\\\/\\\/proxipel.ch\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/proxipel.ch\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proxipel.ch\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/proxipel.svg\",\"contentUrl\":\"https:\\\/\\\/proxipel.ch\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/proxipel.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Proxipel\"},\"image\":{\"@id\":\"https:\\\/\\\/proxipel.ch\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tecnolog\u00eda m\u00f3vil y servicio in situ: una innovaci\u00f3n de Proxipel - Proxipel","description":"Descubre la tecnolog\u00eda m\u00f3vil de Proxipel para convertir los residuos verdes en pellets de madera, una soluci\u00f3n ecol\u00f3gica y eficaz que se puede llevar a cabo in situ","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proxipel.ch\/es\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\/","og_locale":"es_ES","og_type":"article","og_title":"Tecnolog\u00eda m\u00f3vil y servicio in situ: una innovaci\u00f3n de Proxipel - Proxipel","og_description":"Descubre la tecnolog\u00eda m\u00f3vil de Proxipel para convertir los residuos verdes en pellets de madera, una soluci\u00f3n ecol\u00f3gica y eficaz que se puede llevar a cabo in situ","og_url":"https:\/\/proxipel.ch\/es\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\/","og_site_name":"Proxipel","article_modified_time":"2026-07-14T15:55:12+00:00","og_image":[{"width":1600,"height":807,"url":"https:\/\/proxipel.ch\/wp-content\/uploads\/2025\/01\/camion-usine-pellet.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/proxipel.ch\/es\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\/","url":"https:\/\/proxipel.ch\/es\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\/","name":"Tecnolog\u00eda m\u00f3vil y servicio in situ: una innovaci\u00f3n de Proxipel - Proxipel","isPartOf":{"@id":"https:\/\/proxipel.ch\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proxipel.ch\/es\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\/#primaryimage"},"image":{"@id":"https:\/\/proxipel.ch\/es\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\/#primaryimage"},"thumbnailUrl":"https:\/\/proxipel.ch\/wp-content\/uploads\/2025\/01\/camion-usine-pellet.webp","datePublished":"2025-06-02T08:57:06+00:00","dateModified":"2026-07-14T15:55:12+00:00","description":"Descubre la tecnolog\u00eda m\u00f3vil de Proxipel para convertir los residuos verdes en pellets de madera, una soluci\u00f3n ecol\u00f3gica y eficaz que se puede llevar a cabo in situ","breadcrumb":{"@id":"https:\/\/proxipel.ch\/es\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proxipel.ch\/es\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/proxipel.ch\/es\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\/#primaryimage","url":"https:\/\/proxipel.ch\/wp-content\/uploads\/2025\/01\/camion-usine-pellet.webp","contentUrl":"https:\/\/proxipel.ch\/wp-content\/uploads\/2025\/01\/camion-usine-pellet.webp","width":1600,"height":807,"caption":"unit\u00e9 mobile de pelletisation int\u00e9grale"},{"@type":"BreadcrumbList","@id":"https:\/\/proxipel.ch\/es\/tecnologia-movil-y-servicio-in-situ-una-innovacion-de-proxipel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/proxipel.ch\/es\/"},{"@type":"ListItem","position":2,"name":"Tecnolog\u00eda m\u00f3vil y servicio in situ: una innovaci\u00f3n de Proxipel"}]},{"@type":"WebSite","@id":"https:\/\/proxipel.ch\/es\/#website","url":"https:\/\/proxipel.ch\/es\/","name":"Proxipel","description":"La premi\u00e8re unit\u00e9 mobile de pelletisation int\u00e9grale","publisher":{"@id":"https:\/\/proxipel.ch\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proxipel.ch\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/proxipel.ch\/es\/#organization","name":"Proxipel","url":"https:\/\/proxipel.ch\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/proxipel.ch\/es\/#\/schema\/logo\/image\/","url":"https:\/\/proxipel.ch\/wp-content\/uploads\/2024\/04\/proxipel.svg","contentUrl":"https:\/\/proxipel.ch\/wp-content\/uploads\/2024\/04\/proxipel.svg","width":"1024","height":"1024","caption":"Proxipel"},"image":{"@id":"https:\/\/proxipel.ch\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/proxipel.ch\/es\/wp-json\/wp\/v2\/pages\/3150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proxipel.ch\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/proxipel.ch\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/proxipel.ch\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/proxipel.ch\/es\/wp-json\/wp\/v2\/comments?post=3150"}],"version-history":[{"count":1,"href":"https:\/\/proxipel.ch\/es\/wp-json\/wp\/v2\/pages\/3150\/revisions"}],"predecessor-version":[{"id":3152,"href":"https:\/\/proxipel.ch\/es\/wp-json\/wp\/v2\/pages\/3150\/revisions\/3152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proxipel.ch\/es\/wp-json\/wp\/v2\/media\/1231"}],"wp:attachment":[{"href":"https:\/\/proxipel.ch\/es\/wp-json\/wp\/v2\/media?parent=3150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}