{"id":4030,"date":"2026-02-02T14:30:50","date_gmt":"2026-02-02T13:30:50","guid":{"rendered":"https:\/\/proxipel.ch\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/"},"modified":"2026-02-02T14:30:50","modified_gmt":"2026-02-02T13:30:50","slug":"saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets","status":"publish","type":"post","link":"https:\/\/proxipel.ch\/de\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/","title":{"rendered":"S\u00e4gewerk: Verarbeiten Sie Ihre Nebenprodukte vor Ort zu Pellets"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignnone size-full wp-image-2401\" src=\"https:\/\/proxipel.ch\/wp-content\/uploads\/2026\/02\/pellets-de-sciures-1.webp\" alt=\"Verwertung von S\u00e4gewerksnebenprodukten zu Pellets\" width=\"1536\" height=\"1024\" srcset=\"https:\/\/proxipel.ch\/wp-content\/uploads\/2026\/02\/pellets-de-sciures-1.webp 1536w, https:\/\/proxipel.ch\/wp-content\/uploads\/2026\/02\/pellets-de-sciures-1-1280x853.webp 1280w, https:\/\/proxipel.ch\/wp-content\/uploads\/2026\/02\/pellets-de-sciures-1-980x653.webp 980w, https:\/\/proxipel.ch\/wp-content\/uploads\/2026\/02\/pellets-de-sciures-1-480x320.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1536px, 100vw\" \/><\/p>\n<h2><strong>S\u00e4gewerk: Wie w\u00e4re es, wenn Sie Ihre Nebenprodukte zu Pellets verarbeiten w\u00fcrden, ohne in eine station\u00e4re Anlage investieren zu m\u00fcssen?<\/strong><\/h2>\n<p>Jeden Tag fallen in Ihrem S\u00e4gewerk erhebliche Mengen an S\u00e4gewerksnebenprodukten (PCS) an: Fast 50 % des Holzes, das in Ihr S\u00e4gewerk gelangt, wird zu S\u00e4gemehl, Hackschnitzeln, Abschnitten usw. verarbeitet\u2026<\/p>\n<p>Im besten Fall werden diese PCS wie folgt bewertet:<\/p>\n<ul>\n<li>Intern, in Biomassekesseln, die zur Trocknung von Schnittholz eingesetzt werden;<\/li>\n<li>Extern, aus Hackschnitzeln oder Energieholz.<\/li>\n<\/ul>\n<p>F\u00fcr manche werden diese Nebenprodukte schlichtweg nicht wertgesch\u00e4tzt: Sie werden an Landwirte, Landschaftsg\u00e4rtner, Winzer oder H\u00e4cksler abgegeben, um sie kosteng\u00fcnstig zu entsorgen.<\/p>\n<p>Wenn die Nebenprodukte extern verwertet werden, ist das S\u00e4gewerk starken Preisschwankungen ausgesetzt, die mit saisonalen Schwankungen und Bestandsschwankungen zusammenh\u00e4ngen, wodurch die finanzielle Steuerung des Betriebs schwer vorhersehbar wird. Das S\u00e4gewerk wird von diesen externen Absatzm\u00e4rkten abh\u00e4ngig. <\/p>\n<p>Aus logistischer Sicht verursacht die Entsorgung von PCS Kosten f\u00fcr Transport, Umschlag und den Wechsel der Container, ganz zu schweigen von den Lagerungsproblemen, die durch diese Materialien mit geringer Dichte und hohem Volumen entstehen, welche viel Platz beanspruchen und spezielle Einrichtungen erfordern.<\/p>\n<p><a href=\"https:\/\/proxipel.ch\/de\/mobile-technologie-und-vor-ort-service-eine-innovation-von-proxipel\/\"><span style=\"color: #99cc00;\"><strong>Proxipel<\/strong><\/span> <span style=\"color: #99cc00;\">und seine mobile<\/span><\/a> Granuliertechnologie bieten Ihnen eine L\u00f6sung.<\/p>\n<p>Proxipel hat <strong>PROXIFLEX<\/strong> entwickelt, eine mobile Anlage, mit der <a href=\"https:\/\/proxipel.ch\/de\/proxiflex\/\">Nebenprodukte aus der S\u00e4gewerksproduktion zu Granulat verarbeitet<\/a> werden k\u00f6nnen. Der gesamte Prozess \u2013 Zerkleinerung, Trocknung und Granulierung \u2013 wurde auf einem Sattelauflieger integriert, wodurch die Nebenprodukte (S\u00e4gemehl, Hackschnitzel und Feinanteile) direkt vor Ort verwertet werden k\u00f6nnen. <\/p>\n<hr>\n<h3><strong>Warum sollten Sie Ihre S\u00e4gewerksnebenprodukte zu Pellets verarbeiten?<\/strong><\/h3>\n<p>Die Verarbeitung Ihrer Nebenprodukte zu Pellets l\u00f6st drei konkrete Herausforderungen:<\/p>\n<ul>\n<li>Wirtschaftlich: Eine bestehende Ressource besser nutzen und die Abh\u00e4ngigkeit von externen Absatzm\u00e4rkten verringern.<\/li>\n<li>Logistik: Mengen reduzieren, Lagerung vereinfachen, Umschlag und Lagerumschlag begrenzen.<\/li>\n<li>Technische Ziele: Stabilisierung des Feuchtigkeitsgehalts, Homogenisierung des Produkts und Erleichterung der Verwendung (Energie, Einstreu usw.).<\/li>\n<\/ul>\n<hr>\n<h3><strong>PROXIFLEX: Herstellung von Pellets vor Ort aus Ihren Nebenprodukten<\/strong><\/h3>\n<p><a href=\"https:\/\/proxipel.ch\/de\/proxiflex\/\"><span style=\"color: #99cc00;\">PROXIFLEX<\/span><\/a> erm\u00f6glicht es Ihnen, Ihre Nebenprodukte in Pellets umzuwandeln, die der geltenden Norm ISO 17225 entsprechen. Dieses standardisierte Produkt reduziert Ihr Lagervolumen (zur Herstellung von 1 Tonne Pellets werden etwa 7 m\u00b3 S\u00e4gemehl ben\u00f6tigt) und senkt die Logistikkosten erheblich. <\/p>\n<p>PROXIFLEX ist vielseitig einsetzbar und erm\u00f6glicht die Weiterverarbeitung all Ihrer Holznebenprodukte mit einer Korngr\u00f6\u00dfe von maximal 50 mm, einschlie\u00dflich frisch ges\u00e4gter Materialien: Der integrierte Trockner verarbeitet Materialien mit einem Feuchtigkeitsgehalt von bis zu 50 %.<\/p>\n<p>Zul\u00e4ssige Materialien (akzeptierte Werkstoffe)<\/p>\n<ul>\n<li>Holzarten: Nadel- und\/oder Laubholz<\/li>\n<li>Trockenes und\/oder feuchtes S\u00e4gemehl<\/li>\n<li>Sp\u00e4ne<\/li>\n<li>Forstpl\u00e4ttchen<\/li>\n<li>Geldbu\u00dfen<\/li>\n<li>S\u00e4geabschnitte und Restst\u00fccke, vorzerkleinert, sofern die Korngr\u00f6\u00dfe mehr als 50 mm betr\u00e4gt<\/li>\n<\/ul>\n<hr>\n<h3><strong>Ein flexibles Modell: keine Investitionen, keine station\u00e4re Produktionsst\u00e4tte<\/strong><\/h3>\n<p><a href=\"https:\/\/proxipel.ch\/de\/einheit-mieten\/\">PROXIPEL bietet einen bedarfsorientierten Service in Form einer Vermietung an<\/a>. Die Abrechnung erfolgt tageweise; wir stellen Ihnen eine mobile PROXIFLEX-Anlage mit einem qualifizierten Bediener und den erforderlichen Verbrauchsmaterialien zur Verf\u00fcgung. <\/p>\n<p>Der Platzbedarf unserer mobilen Anlage ist relativ gering: Er entspricht dem eines Sattelaufliegers. Zudem ist er nur vor\u00fcbergehend: Die Anlage kommt, nimmt ihre Arbeit auf und f\u00e4hrt wieder ab. Es entsteht keine dauerhafte Fl\u00e4chenbelastung auf Ihrem Gel\u00e4nde.  <\/p>\n<p>Mit dem Mietservice von PROXIPEL k\u00f6nnen Sie Ihre Nebenprodukte zu einem festen und vorhersehbaren Preis verarbeiten, ohne dass Investitionen erforderlich sind. Sie k\u00f6nnen diesen Service je nach Verf\u00fcgbarkeit Ihrer Rohstoffe in regelm\u00e4\u00dfigen Abst\u00e4nden in Anspruch nehmen. <\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-2653\" src=\"https:\/\/proxipel.ch\/wp-content\/uploads\/2026\/02\/etude-de-cas-sciure_2.jpg\" alt=\"Verwertung von S\u00e4gewerkss\u00e4gemehl zu Pellets\" width=\"1031\" height=\"573\" srcset=\"https:\/\/proxipel.ch\/wp-content\/uploads\/2026\/02\/etude-de-cas-sciure_2-980x545.jpg 980w, https:\/\/proxipel.ch\/wp-content\/uploads\/2026\/02\/etude-de-cas-sciure_2-480x267.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1031px, 100vw\" \/><\/p>\n<hr>\n<h3><strong>Absatzm\u00f6glichkeiten: Wozu dienen die im S\u00e4gewerk hergestellten Pellets?<\/strong><\/h3>\n<p>Das von uns f\u00fcr Sie hergestellte Granulat kann direkt f\u00fcr den Eigenverbrauch verwendet oder weiterverkauft werden. Je nach Art des verarbeiteten Rohmaterials erhalten Sie in der Regel Granulat der <a href=\"https:\/\/proxipel.ch\/de\/auswahl-und-eigenschaften-von-pellets\/\"><span style=\"color: #99cc00;\"><strong>Klasse A1<\/strong> oder <strong>A2<\/strong><\/span><\/a>erhalten<span style=\"color: #99cc00;\">.<\/span> Dies kann Ihnen jedoch erst eine <a href=\"https:\/\/proxipel.ch\/de\/umfassende-unterstuetzung-fuer-ihr-projekt\/\">Charakterisierungsanalyse des Pellets<\/a> best\u00e4tigen. <\/p>\n<p>M\u00f6gliche Absatzm\u00e4rkte f\u00fcr Ihr Granulat<\/p>\n<ul>\n<li>Direktverkauf aus Ihrem \u201eShowroom\u201c an Ihre Privat- und Gesch\u00e4ftskunden<\/li>\n<li>Privatkundenmarkt: f\u00fcr Pellet\u00f6fen, die in der Schweiz, in Frankreich und in Belgien weit verbreitet sind<\/li>\n<li>Kommunen: Viele Gemeinden nutzen Pellets in Heizkesseln, um ihre \u00f6ffentlichen Geb\u00e4ude (Schulen, Rathaus, st\u00e4dtisches Schwimmbad, Seniorenheim usw.) zu beheizen. Sicherlich gibt es auch in Ihrer Gemeinde solche Einrichtungen. <\/li>\n<li>Einstreu f\u00fcr Tiere: Gest\u00fcte und andere Reitzentren geh\u00f6ren zu den bedeutenden Abnehmern von Granulat.<\/li>\n<\/ul>\n<hr>\n<h3><strong>Den CO\u2082-Fu\u00dfabdruck verringern und die lokale Verankerung st\u00e4rken<\/strong><\/h3>\n<p>\u00dcber die unmittelbare Rentabilit\u00e4t hinaus ver\u00e4ndert der Einsatz der Proxipel-L\u00f6sung das Umweltprofil Ihres S\u00e4gewerks. In einem Markt, der zunehmend auf die Herkunft der Produkte achtet, stellt dies einen konkreten Kommunikationshebel dar. <\/p>\n<p>Kurze Lieferkette: vom Baumstamm bis zum Pellet<\/p>\n<p>Traditionell werden die Nebenprodukte eines S\u00e4gewerks per Lkw \u00fcber Dutzende oder sogar Hunderte von Kilometern zu einer Pelletieranlage transportiert, bevor sie manchmal in dieselbe Region zur\u00fcckkehren, um dort verbraucht zu werden, oder sogar zum urspr\u00fcnglichen S\u00e4gewerk, um dort weiterverkauft zu werden.<\/p>\n<p>Mit Proxipel wird der Transport von Rohstoffen auf null reduziert. Die Umwandlung erfolgt direkt vor Ort. Sie werden zum Erzeuger einer Energie, die nur eine sehr kurze Transportstrecke zur\u00fcckgelegt hat.  <\/p>\n<p>CO\u2082-Bilanz: Optimierung der Logistik und Verdichtung<\/p>\n<p>Die Logistik im Zusammenhang mit S\u00e4gemehl ist naturgem\u00e4\u00df wenig effizient: Es wird viel Luft und Wasser transportiert.<\/p>\n<ul>\n<li>Verdichtung vor Ort: Indem Sie feuchtes, volumin\u00f6ses S\u00e4gemehl direkt vor Ort in dichte, trockene Pellets umwandeln, reduzieren Sie die Anzahl der Lkw-Fahrten, die zum Abtransport derselben Energiemenge erforderlich sind, um das 5- bis 6-Fache.<\/li>\n<li>Energieeffizienz: Die von Proxipel eingesetzte Technologie ist darauf ausgelegt, den Energieverbrauch beim Trocknen und Pressen zu optimieren, wodurch Pellets mit einer geringeren CO\u2082-Bilanz als die in einer Fabrik hergestellten gew\u00e4hrleistet werden (21 g CO\u2082\/kWh gegen\u00fcber 38 g CO\u2082\/kWh).<\/li>\n<\/ul>\n<p>Regionale Verankerung: ein konkretes Verkaufsargument<\/p>\n<p>Wenn Sie zu Hause Pellets herstellen, bieten Sie Ihren Kunden (Privatpersonen und Gewerbetreibenden) einen \u201ezu 100 % lokalen\u201c Brennstoff an.<\/p>\n<p>Machen Sie dies zu einem Verkaufsargument: \u201eDas Holz wurde in unseren W\u00e4ldern geschlagen, in unseren Werkst\u00e4tten ges\u00e4gt und auf unserem Hof zu Pellets verarbeitet.\u201c<\/p>\n<p>Werden Sie zu einem Akteur der Kreislaufwirtschaft: Sie zeigen, dass nichts verloren geht. Was einst als sperriger Abfall galt, wird zu einer wertvollen Ressource, die Sie von Anfang bis Ende kontrollieren. <\/p>\n<p>Mit Ihrer Entscheidung f\u00fcr die mobile Granulieranlage von Proxipel zeigen Sie, dass Ihr S\u00e4gewerk innovativ vorgeht, um die Ressourcen Ihrer Region zu schonen und gleichzeitig die mit dem Stra\u00dfentransport verbundenen Belastungen zu verringern.<\/p>\n<hr>\n<h3><strong>Wie funktioniert das auf Ihrer Website?<\/strong><\/h3>\n<p>Unsere mobile Anlage ist vollst\u00e4ndig in einen Sattelauflieger integriert. Sie wird direkt zum Lagerort Ihrer Abf\u00e4lle transportiert. Die Installation erfolgt z\u00fcgig:  <\/p>\n<ul>\n<li>Zubereitung und Vorbereitung: etwa eine Stunde<\/li>\n<li>Betrieb: Die Anlage ist dank ihres Dieselgenerators autark, kann jedoch auch an das Stromnetz angeschlossen werden, sofern Sie \u00fcber einen dreiphasigen Industrieanschluss mit 260 kVA verf\u00fcgen (erm\u00e4\u00dfigter Mietpreis). Die Durchsatzleistung betr\u00e4gt durchschnittlich 1 t\/h. Diese h\u00e4ngt von der Art des Aufgabeguts und dessen Feuchtigkeit ab.  <\/li>\n<li>Ausgabe des Granulats durch Ausblasen: Am Maschinenausgang kann das Granulat in einen Big Bag, einen Container, ein Silo oder einen anderen Beh\u00e4lter Ihrer Wahl ausgeblasen werden.<\/li>\n<\/ul>\n<p><strong>Materielle und logistische Voraussetzungen (bitte einplanen)<\/strong><\/p>\n<ul>\n<li>Ein Vorrat an Nebenprodukten mit einer Korngr\u00f6\u00dfe von maximal 50 mm und einer Feuchtigkeit von maximal 50 %. F\u00fcr Ihre Holzabf\u00e4lle oder S\u00e4gesp\u00e4ne, die diese Korngr\u00f6\u00dfe \u00fcberschreiten, ist eine Vorzerkleinerung vorzusehen. Sie k\u00f6nnen verschiedene Arten von Nebenprodukten haben (beispielsweise S\u00e4gemehl und Holzhackschnitzel): Diese werden nacheinander verarbeitet.  <\/li>\n<li>Der Lagerbestand reicht aus, um f\u00fcnf aufeinanderfolgende Tage der Granulierung zu gew\u00e4hrleisten, was etwa 50 t entspricht.<\/li>\n<li>Materialien, die frei von Fremdk\u00f6rpern (Steine, Metalle, Kunststoffe usw.) sind.<\/li>\n<li>Ein ausreichend ebener und stabiler Standort, um den Anh\u00e4nger aufzustellen (Ma\u00dfe im aufgestellten Zustand: 16 \u00d7 5 m).<\/li>\n<li>Ein Beschicker steht zur Verf\u00fcgung, um den Einlauftrichter zu bef\u00fcllen.<\/li>\n<li>Ein Wasseranschluss mit einem Schlauch.<\/li>\n<li>Ein Lagerort f\u00fcr Ihre Pellets, gesch\u00fctzt vor Feuchtigkeit.<\/li>\n<\/ul>\n<hr>\n<h3><strong>Sind Sie bereit, Ihre Nebenprodukte in Pellets zu verwandeln und die Kontrolle \u00fcber Ihre Verwertung zur\u00fcckzugewinnen?<\/strong> <span style=\"color: #99cc00;\"><a style=\"color: #99cc00;\" href=\"https:\/\/proxipel.ch\/de\/kontakt\/\">Wenden Sie sich an Proxipel<\/a><\/span> f\u00fcr eine Analyse Ihres Nebenproduktvorkommens<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e4gewerk: Wie w\u00e4re es, wenn Sie Ihre Nebenprodukte zu Pellets verarbeiten w\u00fcrden, ohne in eine station\u00e4re Anlage investieren zu m\u00fcssen? Jeden Tag fallen in Ihrem S\u00e4gewerk erhebliche Mengen an S\u00e4gewerksnebenprodukten (PCS) an: Fast 50 % des Holzes, das in Ihr S\u00e4gewerk gelangt, wird zu S\u00e4gemehl, Hackschnitzeln, Abschnitten usw. verarbeitet\u2026 Im besten Fall werden diese PCS [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":2403,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[48],"tags":[],"class_list":["post-4030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e4gewerk: Verarbeiten Sie Ihre Nebenprodukte vor Ort zu Pellets - Proxipel<\/title>\n<meta name=\"description\" content=\"Verarbeiten Sie Ihre S\u00e4gewerksnebenprodukte vor Ort zu Pellets \u2013 mit Proxipel, einer mobilen Anlage, die Zerkleinerung, Trocknung und Pelletierung in einem Ger\u00e4t vereint\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proxipel.ch\/de\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e4gewerk: Verarbeiten Sie Ihre Nebenprodukte vor Ort zu Pellets - Proxipel\" \/>\n<meta property=\"og:description\" content=\"Verarbeiten Sie Ihre S\u00e4gewerksnebenprodukte vor Ort zu Pellets \u2013 mit Proxipel, einer mobilen Anlage, die Zerkleinerung, Trocknung und Pelletierung in einem Ger\u00e4t vereint\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proxipel.ch\/de\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxipel\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-02T13:30:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proxipel.ch\/wp-content\/uploads\/2026\/02\/pellets-de-sciures-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Bertrand Bordenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bertrand Bordenave\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\\\/\"},\"author\":{\"name\":\"Bertrand Bordenave\",\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/#\\\/schema\\\/person\\\/14b4c44ffd52db22ee770bc4b0ce909a\"},\"headline\":\"S\u00e4gewerk: Verarbeiten Sie Ihre Nebenprodukte vor Ort zu Pellets\",\"datePublished\":\"2026-02-02T13:30:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\\\/\"},\"wordCount\":1317,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proxipel.ch\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/pellets-de-sciures-1.webp\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/proxipel.ch\\\/de\\\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\\\/\",\"url\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\\\/\",\"name\":\"S\u00e4gewerk: Verarbeiten Sie Ihre Nebenprodukte vor Ort zu Pellets - Proxipel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proxipel.ch\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/pellets-de-sciures-1.webp\",\"datePublished\":\"2026-02-02T13:30:50+00:00\",\"description\":\"Verarbeiten Sie Ihre S\u00e4gewerksnebenprodukte vor Ort zu Pellets \u2013 mit Proxipel, einer mobilen Anlage, die Zerkleinerung, Trocknung und Pelletierung in einem Ger\u00e4t vereint\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proxipel.ch\\\/de\\\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proxipel.ch\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/pellets-de-sciures-1.webp\",\"contentUrl\":\"https:\\\/\\\/proxipel.ch\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/pellets-de-sciures-1.webp\",\"width\":1536,\"height\":1024,\"caption\":\"valoris\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e4gewerk: Verarbeiten Sie Ihre Nebenprodukte vor Ort zu Pellets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/\",\"name\":\"Proxipel\",\"description\":\"La premi\u00e8re unit\u00e9 mobile de pelletisation int\u00e9grale\",\"publisher\":{\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/#organization\",\"name\":\"Proxipel\",\"url\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proxipel.ch\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/proxipel.svg\",\"contentUrl\":\"https:\\\/\\\/proxipel.ch\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/proxipel.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Proxipel\"},\"image\":{\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/#\\\/schema\\\/person\\\/14b4c44ffd52db22ee770bc4b0ce909a\",\"name\":\"Bertrand Bordenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e17b5e0af21b580beae0180a27aa4d7661a659aea637f7c5133d8954df6b313b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e17b5e0af21b580beae0180a27aa4d7661a659aea637f7c5133d8954df6b313b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e17b5e0af21b580beae0180a27aa4d7661a659aea637f7c5133d8954df6b313b?s=96&d=mm&r=g\",\"caption\":\"Bertrand Bordenave\"},\"url\":\"https:\\\/\\\/proxipel.ch\\\/de\\\/author\\\/b-bordenaveproxipel-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e4gewerk: Verarbeiten Sie Ihre Nebenprodukte vor Ort zu Pellets - Proxipel","description":"Verarbeiten Sie Ihre S\u00e4gewerksnebenprodukte vor Ort zu Pellets \u2013 mit Proxipel, einer mobilen Anlage, die Zerkleinerung, Trocknung und Pelletierung in einem Ger\u00e4t vereint","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proxipel.ch\/de\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/","og_locale":"de_DE","og_type":"article","og_title":"S\u00e4gewerk: Verarbeiten Sie Ihre Nebenprodukte vor Ort zu Pellets - Proxipel","og_description":"Verarbeiten Sie Ihre S\u00e4gewerksnebenprodukte vor Ort zu Pellets \u2013 mit Proxipel, einer mobilen Anlage, die Zerkleinerung, Trocknung und Pelletierung in einem Ger\u00e4t vereint","og_url":"https:\/\/proxipel.ch\/de\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/","og_site_name":"Proxipel","article_published_time":"2026-02-02T13:30:50+00:00","og_image":[{"width":1536,"height":1024,"url":"https:\/\/proxipel.ch\/wp-content\/uploads\/2026\/02\/pellets-de-sciures-1.webp","type":"image\/webp"}],"author":"Bertrand Bordenave","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Bertrand Bordenave","Gesch\u00e4tzte Lesezeit":"7\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proxipel.ch\/de\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/#article","isPartOf":{"@id":"https:\/\/proxipel.ch\/de\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/"},"author":{"name":"Bertrand Bordenave","@id":"https:\/\/proxipel.ch\/de\/#\/schema\/person\/14b4c44ffd52db22ee770bc4b0ce909a"},"headline":"S\u00e4gewerk: Verarbeiten Sie Ihre Nebenprodukte vor Ort zu Pellets","datePublished":"2026-02-02T13:30:50+00:00","mainEntityOfPage":{"@id":"https:\/\/proxipel.ch\/de\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/"},"wordCount":1317,"commentCount":0,"publisher":{"@id":"https:\/\/proxipel.ch\/de\/#organization"},"image":{"@id":"https:\/\/proxipel.ch\/de\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/#primaryimage"},"thumbnailUrl":"https:\/\/proxipel.ch\/wp-content\/uploads\/2026\/02\/pellets-de-sciures-1.webp","articleSection":["Blog"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/proxipel.ch\/de\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/proxipel.ch\/de\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/","url":"https:\/\/proxipel.ch\/de\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/","name":"S\u00e4gewerk: Verarbeiten Sie Ihre Nebenprodukte vor Ort zu Pellets - Proxipel","isPartOf":{"@id":"https:\/\/proxipel.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proxipel.ch\/de\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/#primaryimage"},"image":{"@id":"https:\/\/proxipel.ch\/de\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/#primaryimage"},"thumbnailUrl":"https:\/\/proxipel.ch\/wp-content\/uploads\/2026\/02\/pellets-de-sciures-1.webp","datePublished":"2026-02-02T13:30:50+00:00","description":"Verarbeiten Sie Ihre S\u00e4gewerksnebenprodukte vor Ort zu Pellets \u2013 mit Proxipel, einer mobilen Anlage, die Zerkleinerung, Trocknung und Pelletierung in einem Ger\u00e4t vereint","breadcrumb":{"@id":"https:\/\/proxipel.ch\/de\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proxipel.ch\/de\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/proxipel.ch\/de\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/#primaryimage","url":"https:\/\/proxipel.ch\/wp-content\/uploads\/2026\/02\/pellets-de-sciures-1.webp","contentUrl":"https:\/\/proxipel.ch\/wp-content\/uploads\/2026\/02\/pellets-de-sciures-1.webp","width":1536,"height":1024,"caption":"valoris"},{"@type":"BreadcrumbList","@id":"https:\/\/proxipel.ch\/de\/saegewerk-verarbeiten-sie-ihre-nebenprodukte-vor-ort-zu-pellets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/proxipel.ch\/de\/"},{"@type":"ListItem","position":2,"name":"S\u00e4gewerk: Verarbeiten Sie Ihre Nebenprodukte vor Ort zu Pellets"}]},{"@type":"WebSite","@id":"https:\/\/proxipel.ch\/de\/#website","url":"https:\/\/proxipel.ch\/de\/","name":"Proxipel","description":"La premi\u00e8re unit\u00e9 mobile de pelletisation int\u00e9grale","publisher":{"@id":"https:\/\/proxipel.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proxipel.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/proxipel.ch\/de\/#organization","name":"Proxipel","url":"https:\/\/proxipel.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/proxipel.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/proxipel.ch\/wp-content\/uploads\/2024\/04\/proxipel.svg","contentUrl":"https:\/\/proxipel.ch\/wp-content\/uploads\/2024\/04\/proxipel.svg","width":"1024","height":"1024","caption":"Proxipel"},"image":{"@id":"https:\/\/proxipel.ch\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/proxipel.ch\/de\/#\/schema\/person\/14b4c44ffd52db22ee770bc4b0ce909a","name":"Bertrand Bordenave","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e17b5e0af21b580beae0180a27aa4d7661a659aea637f7c5133d8954df6b313b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e17b5e0af21b580beae0180a27aa4d7661a659aea637f7c5133d8954df6b313b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e17b5e0af21b580beae0180a27aa4d7661a659aea637f7c5133d8954df6b313b?s=96&d=mm&r=g","caption":"Bertrand Bordenave"},"url":"https:\/\/proxipel.ch\/de\/author\/b-bordenaveproxipel-com\/"}]}},"_links":{"self":[{"href":"https:\/\/proxipel.ch\/de\/wp-json\/wp\/v2\/posts\/4030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proxipel.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proxipel.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proxipel.ch\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/proxipel.ch\/de\/wp-json\/wp\/v2\/comments?post=4030"}],"version-history":[{"count":0,"href":"https:\/\/proxipel.ch\/de\/wp-json\/wp\/v2\/posts\/4030\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proxipel.ch\/de\/wp-json\/wp\/v2\/media\/2403"}],"wp:attachment":[{"href":"https:\/\/proxipel.ch\/de\/wp-json\/wp\/v2\/media?parent=4030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proxipel.ch\/de\/wp-json\/wp\/v2\/categories?post=4030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proxipel.ch\/de\/wp-json\/wp\/v2\/tags?post=4030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}